{"id":155,"count":0,"description":"","link":"https:\/\/delicooks.com\/en\/pantry\/ingredients\/vegetables\/","name":"Vegetables","slug":"vegetables","taxonomy":"category","parent":152,"meta":[],"z_taxonomy_image_url":"https:\/\/delicooks.com\/wp-content\/plugins\/categories-images\/assets\/images\/placeholder.png","_links":{"self":[{"href":"https:\/\/delicooks.com\/en\/wp-json\/wp\/v2\/categories\/155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/delicooks.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/delicooks.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/delicooks.com\/en\/wp-json\/wp\/v2\/categories\/152"}],"wp:post_type":[{"href":"https:\/\/delicooks.com\/en\/wp-json\/wp\/v2\/posts?categories=155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}